{"id":23820,"date":"2025-11-25T19:59:32","date_gmt":"2025-11-25T18:59:32","guid":{"rendered":"https:\/\/balteschwiler.ch\/?page_id=23820"},"modified":"2025-11-25T20:18:37","modified_gmt":"2025-11-25T19:18:37","slug":"dependance-de-lhotel-palace-muerren","status":"publish","type":"page","link":"https:\/\/balteschwiler.ch\/fr\/references\/dependance-de-lhotel-palace-muerren\/","title":{"rendered":"D\u00e9pendance de l\u2019H\u00f4tel Palace M\u00fcrren"},"content":{"rendered":"<div class=\"gb-container gb-container-6ec57639 loadondesktop\"><div class=\"gb-inside-container\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-d212ffc2\">\n<div class=\"gb-grid-column gb-grid-column-6290146c\"><div class=\"gb-container gb-container-6290146c\"><div class=\"gb-inside-container\">\n\n<p class=\"gb-headline gb-headline-a9091560 gb-headline-text\"><strong>Projet de r\u00e9f\u00e9rence<\/strong><\/p>\n\n\n\n<h1 class=\"gb-headline gb-headline-ae3932be gb-headline-text\"><strong>D\u00e9pendance de l\u2019H\u00f4tel Palace, M\u00fcrren<\/strong><\/h1>\n\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-0f7de636\"><div class=\"gb-inside-container\">\n\n<div class=\"wp-block-uagb-slider uagb-block-fcd85a6a uagb-slider-container\"><div class=\"uagb-slides uagb-swiper\"><div class=\"swiper-wrapper\">\n<div class=\"wp-block-uagb-slider-child uagb-slider-child-wrap swiper-slide uagb-block-73cf9880\"><div class=\"swiper-content\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/Muerren_Palace_Aussenaufnahme_Winter-15-1-scaled.jpg\" alt=\"\" class=\"wp-image-23815\" srcset=\"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/Muerren_Palace_Aussenaufnahme_Winter-15-1-scaled.jpg 2560w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/Muerren_Palace_Aussenaufnahme_Winter-15-1-300x225.jpg 300w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/Muerren_Palace_Aussenaufnahme_Winter-15-1-1024x768.jpg 1024w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/Muerren_Palace_Aussenaufnahme_Winter-15-1-768x576.jpg 768w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/Muerren_Palace_Aussenaufnahme_Winter-15-1-1536x1152.jpg 1536w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/Muerren_Palace_Aussenaufnahme_Winter-15-1-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-slider-child uagb-slider-child-wrap swiper-slide uagb-block-297ab518\"><div class=\"swiper-content\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1438\" src=\"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/DJI_20250115195412_0594_D-scaled.jpg\" alt=\"\" class=\"wp-image-23823\" srcset=\"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/DJI_20250115195412_0594_D-scaled.jpg 2560w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/DJI_20250115195412_0594_D-300x169.jpg 300w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/DJI_20250115195412_0594_D-1024x575.jpg 1024w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/DJI_20250115195412_0594_D-768x432.jpg 768w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/DJI_20250115195412_0594_D-1536x863.jpg 1536w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/DJI_20250115195412_0594_D-2048x1151.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-slider-child uagb-slider-child-wrap swiper-slide uagb-block-2128fd97\"><div class=\"swiper-content\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/03_Muerren-Palace-Suite-1-scaled.jpg\" alt=\"\" class=\"wp-image-23825\" srcset=\"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/03_Muerren-Palace-Suite-1-scaled.jpg 2560w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/03_Muerren-Palace-Suite-1-300x200.jpg 300w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/03_Muerren-Palace-Suite-1-1024x683.jpg 1024w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/03_Muerren-Palace-Suite-1-768x512.jpg 768w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/03_Muerren-Palace-Suite-1-1536x1024.jpg 1536w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/03_Muerren-Palace-Suite-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-slider-child uagb-slider-child-wrap swiper-slide uagb-block-d680947f\"><div class=\"swiper-content\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/IMG_3324-1-scaled.jpg\" alt=\"\" class=\"wp-image-23827\" srcset=\"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/IMG_3324-1-scaled.jpg 2560w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/IMG_3324-1-300x225.jpg 300w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/IMG_3324-1-1024x768.jpg 1024w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/IMG_3324-1-768x576.jpg 768w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/IMG_3324-1-1536x1152.jpg 1536w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/IMG_3324-1-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-slider-child uagb-slider-child-wrap swiper-slide uagb-block-2977e9fc\"><div class=\"swiper-content\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/2-1-scaled.jpeg\" alt=\"\" class=\"wp-image-23836\" srcset=\"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/2-1-scaled.jpeg 2560w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/2-1-300x225.jpeg 300w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/2-1-1024x768.jpeg 1024w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/2-1-768x576.jpeg 768w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/2-1-1536x1152.jpeg 1536w, https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/2-1-2048x1536.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-slider-child uagb-slider-child-wrap swiper-slide uagb-block-692daf65\"><div class=\"swiper-content\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/Bild-20241012-124502-c3911807-2-scaled.jpeg\" alt=\"\" class=\"wp-image-23839\"\/><\/figure>\n<\/div><\/div>\n<\/div><\/div><div class=\"swiper-button-prev\"><\/div><div class=\"swiper-button-next\"><\/div><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<hr class=\"wp-block-separator has-text-color has-contrast-color has-alpha-channel-opacity has-contrast-background-color has-background\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>B\u00e2timent en bois de cinq \u00e9tages \u00e0 1\u2019650 m d\u2019altitude, dans le village sans voitures de M\u00fcrren<\/strong><\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">\u00c0 1\u2019650 m d\u2019altitude, dans le village sans voitures de M\u00fcrren, la nouvelle d\u00e9pendance de l\u2019historique H\u00f4tel Palace a vu le jour \u2013 un b\u00e2timent elliptique en bois de cinq \u00e9tages qui compl\u00e8te harmonieusement l\u2019\u00e9difice principal. Le bureau d\u2019architecture Ducksch Anliker AG et l\u2019entreprise Wenger Holzbau AG ont r\u00e9alis\u00e9 un ouvrage d\u2019exception alliant esth\u00e9tique alpine et pr\u00e9cision technique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La soci\u00e9t\u00e9 Balteschwiler SA a assur\u00e9 l\u2019usinage pr\u00e9cis des \u00e9l\u00e9ments CLT et Kerto (plus de 1\u2019500 m\u00b2 au total), le parement en panneaux Fermacell, ainsi que la livraison just-in-time jusqu\u2019\u00e0 M\u00fcrren \u2013 une prouesse logistique \u00e0 plus de 1\u2019600 m\u00e8tres d\u2019altitude. Gr\u00e2ce \u00e0 une pr\u00e9fabrication soign\u00e9e, les \u00e9l\u00e9ments courbes ont pu \u00eatre assembl\u00e9s avec une pr\u00e9cision remarquable.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Ce projet illustre la parfaite synergie entre architecture contemporaine, construction bois durable et savoir-faire industriel \u2013 un exemple embl\u00e9matique du g\u00e9nie constructif alpin.<\/p>\n\n\n<div class=\"gb-button-wrapper gb-button-wrapper-7c34dbc8\">\n\n<a class=\"gb-button gb-button-b8c1b8eb gb-button-text smooth-scroll button-border-none\" href=\"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/2024-clt-abbund-hotel-muerren-palace-wenger-fr.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Fiche de r\u00e9f\u00e9rence<\/a>\n\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column spalte-custom-space-left is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<hr class=\"wp-block-separator has-text-color has-contrast-color has-alpha-channel-opacity has-contrast-background-color has-background\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ann\u00e9e de construction<\/strong><br>2024<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Type de b\u00e2timent \/ usage<br><\/strong>Nouvelle construction, d\u00e9pendance h\u00f4teli\u00e8re<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ma\u00eetre d\u02bcouvrage<br><\/strong>M\u00fcrren Investment et<br>Management AG, H\u00f4tel Palace M\u00fcrren<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><strong>Architecte :<\/strong><\/strong><br>Ducksch Anliker AG, Langenthal<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Partenaire d\u02bcex\u00e9cution\/Client<\/strong><br>Wenger Holzbau AG,<br>Steffisburg<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Services Balteschwiler utilis\u00e9s <\/strong><br>CLT avec usinage sur mesure, Kerto avec usinage sur mesure, Parement Fermacell, Livraison<\/p>\n<\/div>\n<\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>B\u00e2timent en bois de cinq \u00e9tages \u00e0 1\u2019650 m d\u2019altitude, dans le village sans voitures de M\u00fcrren \u00c0 1\u2019650 m d\u2019altitude, dans le village sans voitures de M\u00fcrren, la nouvelle &#8230; <a title=\"D\u00e9pendance de l\u2019H\u00f4tel Palace M\u00fcrren\" class=\"read-more\" href=\"https:\/\/balteschwiler.ch\/fr\/references\/dependance-de-lhotel-palace-muerren\/\" aria-label=\"En savoir plus sur D\u00e9pendance de l\u2019H\u00f4tel Palace M\u00fcrren\">Mehr<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"parent":8941,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-23820","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9pendance de l\u2019H\u00f4tel Palace M\u00fcrren - Balteschwiler AG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/balteschwiler.ch\/fr\/references\/dependance-de-lhotel-palace-muerren\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9pendance de l\u2019H\u00f4tel Palace M\u00fcrren - Balteschwiler AG\" \/>\n<meta property=\"og:description\" content=\"B\u00e2timent en bois de cinq \u00e9tages \u00e0 1\u2019650 m d\u2019altitude, dans le village sans voitures de M\u00fcrren \u00c0 1\u2019650 m d\u2019altitude, dans le village sans voitures de M\u00fcrren, la nouvelle ... Mehr\" \/>\n<meta property=\"og:url\" content=\"https:\/\/balteschwiler.ch\/fr\/references\/dependance-de-lhotel-palace-muerren\/\" \/>\n<meta property=\"og:site_name\" content=\"Balteschwiler AG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/balteschwiler\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-25T19:18:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/Muerren_Palace_Aussenaufnahme_Winter-15-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/balteschwiler.ch\\\/fr\\\/references\\\/dependance-de-lhotel-palace-muerren\\\/\",\"url\":\"https:\\\/\\\/balteschwiler.ch\\\/fr\\\/references\\\/dependance-de-lhotel-palace-muerren\\\/\",\"name\":\"D\u00e9pendance de l\u2019H\u00f4tel Palace M\u00fcrren - Balteschwiler AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/balteschwiler.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/balteschwiler.ch\\\/fr\\\/references\\\/dependance-de-lhotel-palace-muerren\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/balteschwiler.ch\\\/fr\\\/references\\\/dependance-de-lhotel-palace-muerren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/balteschwiler.ch\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Muerren_Palace_Aussenaufnahme_Winter-15-1-scaled.jpg\",\"datePublished\":\"2025-11-25T18:59:32+00:00\",\"dateModified\":\"2025-11-25T19:18:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/balteschwiler.ch\\\/fr\\\/references\\\/dependance-de-lhotel-palace-muerren\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/balteschwiler.ch\\\/fr\\\/references\\\/dependance-de-lhotel-palace-muerren\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/balteschwiler.ch\\\/fr\\\/references\\\/dependance-de-lhotel-palace-muerren\\\/#primaryimage\",\"url\":\"https:\\\/\\\/balteschwiler.ch\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Muerren_Palace_Aussenaufnahme_Winter-15-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/balteschwiler.ch\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Muerren_Palace_Aussenaufnahme_Winter-15-1-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/balteschwiler.ch\\\/fr\\\/references\\\/dependance-de-lhotel-palace-muerren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"R\u00e9f\u00e9rences\",\"item\":\"https:\\\/\\\/balteschwiler.ch\\\/fr\\\/references\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9pendance de l\u2019H\u00f4tel Palace M\u00fcrren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/balteschwiler.ch\\\/#website\",\"url\":\"https:\\\/\\\/balteschwiler.ch\\\/\",\"name\":\"Balteschwiler AG\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/balteschwiler.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/balteschwiler.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/balteschwiler.ch\\\/#organization\",\"name\":\"Balteschwiler AG\",\"url\":\"https:\\\/\\\/balteschwiler.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/balteschwiler.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/balteschwiler.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/rz_BAL_Logo_d_rgb.png\",\"contentUrl\":\"https:\\\/\\\/balteschwiler.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/rz_BAL_Logo_d_rgb.png\",\"width\":1182,\"height\":224,\"caption\":\"Balteschwiler AG\"},\"image\":{\"@id\":\"https:\\\/\\\/balteschwiler.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/balteschwiler\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9pendance de l\u2019H\u00f4tel Palace M\u00fcrren - Balteschwiler AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/balteschwiler.ch\/fr\/references\/dependance-de-lhotel-palace-muerren\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9pendance de l\u2019H\u00f4tel Palace M\u00fcrren - Balteschwiler AG","og_description":"B\u00e2timent en bois de cinq \u00e9tages \u00e0 1\u2019650 m d\u2019altitude, dans le village sans voitures de M\u00fcrren \u00c0 1\u2019650 m d\u2019altitude, dans le village sans voitures de M\u00fcrren, la nouvelle ... Mehr","og_url":"https:\/\/balteschwiler.ch\/fr\/references\/dependance-de-lhotel-palace-muerren\/","og_site_name":"Balteschwiler AG","article_publisher":"https:\/\/www.facebook.com\/balteschwiler","article_modified_time":"2025-11-25T19:18:37+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/Muerren_Palace_Aussenaufnahme_Winter-15-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/balteschwiler.ch\/fr\/references\/dependance-de-lhotel-palace-muerren\/","url":"https:\/\/balteschwiler.ch\/fr\/references\/dependance-de-lhotel-palace-muerren\/","name":"D\u00e9pendance de l\u2019H\u00f4tel Palace M\u00fcrren - Balteschwiler AG","isPartOf":{"@id":"https:\/\/balteschwiler.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/balteschwiler.ch\/fr\/references\/dependance-de-lhotel-palace-muerren\/#primaryimage"},"image":{"@id":"https:\/\/balteschwiler.ch\/fr\/references\/dependance-de-lhotel-palace-muerren\/#primaryimage"},"thumbnailUrl":"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/Muerren_Palace_Aussenaufnahme_Winter-15-1-scaled.jpg","datePublished":"2025-11-25T18:59:32+00:00","dateModified":"2025-11-25T19:18:37+00:00","breadcrumb":{"@id":"https:\/\/balteschwiler.ch\/fr\/references\/dependance-de-lhotel-palace-muerren\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/balteschwiler.ch\/fr\/references\/dependance-de-lhotel-palace-muerren\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/balteschwiler.ch\/fr\/references\/dependance-de-lhotel-palace-muerren\/#primaryimage","url":"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/Muerren_Palace_Aussenaufnahme_Winter-15-1-scaled.jpg","contentUrl":"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2025\/11\/Muerren_Palace_Aussenaufnahme_Winter-15-1-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/balteschwiler.ch\/fr\/references\/dependance-de-lhotel-palace-muerren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"R\u00e9f\u00e9rences","item":"https:\/\/balteschwiler.ch\/fr\/references\/"},{"@type":"ListItem","position":2,"name":"D\u00e9pendance de l\u2019H\u00f4tel Palace M\u00fcrren"}]},{"@type":"WebSite","@id":"https:\/\/balteschwiler.ch\/#website","url":"https:\/\/balteschwiler.ch\/","name":"Balteschwiler AG","description":"","publisher":{"@id":"https:\/\/balteschwiler.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/balteschwiler.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/balteschwiler.ch\/#organization","name":"Balteschwiler AG","url":"https:\/\/balteschwiler.ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/balteschwiler.ch\/#\/schema\/logo\/image\/","url":"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2022\/09\/rz_BAL_Logo_d_rgb.png","contentUrl":"https:\/\/balteschwiler.ch\/wp-content\/uploads\/2022\/09\/rz_BAL_Logo_d_rgb.png","width":1182,"height":224,"caption":"Balteschwiler AG"},"image":{"@id":"https:\/\/balteschwiler.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/balteschwiler"]}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Franziska H\u00e4nni","author_link":"https:\/\/balteschwiler.ch\/fr\/author\/f-haenni\/"},"uagb_comment_info":0,"uagb_excerpt":"B\u00e2timent en bois de cinq \u00e9tages \u00e0 1\u2019650 m d\u2019altitude, dans le village sans voitures de M\u00fcrren \u00c0 1\u2019650 m d\u2019altitude, dans le village sans voitures de M\u00fcrren, la nouvelle ... Mehr","_links":{"self":[{"href":"https:\/\/balteschwiler.ch\/fr\/wp-json\/wp\/v2\/pages\/23820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/balteschwiler.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/balteschwiler.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/balteschwiler.ch\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/balteschwiler.ch\/fr\/wp-json\/wp\/v2\/comments?post=23820"}],"version-history":[{"count":1,"href":"https:\/\/balteschwiler.ch\/fr\/wp-json\/wp\/v2\/pages\/23820\/revisions"}],"predecessor-version":[{"id":23852,"href":"https:\/\/balteschwiler.ch\/fr\/wp-json\/wp\/v2\/pages\/23820\/revisions\/23852"}],"up":[{"embeddable":true,"href":"https:\/\/balteschwiler.ch\/fr\/wp-json\/wp\/v2\/pages\/8941"}],"wp:attachment":[{"href":"https:\/\/balteschwiler.ch\/fr\/wp-json\/wp\/v2\/media?parent=23820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}